{"id":4,"count":148,"description":"","link":"https:\/\/storymamas.com\/wp\/category\/childrens-books\/","name":"Children's Books","slug":"childrens-books","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Children&#039;s Books Archives - Storymamas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/storymamas.com\/wp\/category\/childrens-books\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Children&#039;s Books Archives - Storymamas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/storymamas.com\/wp\/category\/childrens-books\/\" \/>\n<meta property=\"og:site_name\" content=\"Storymamas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/storymamas.com\/wp\/category\/childrens-books\/\",\"url\":\"https:\/\/storymamas.com\/wp\/category\/childrens-books\/\",\"name\":\"Children's Books Archives - Storymamas\",\"isPartOf\":{\"@id\":\"https:\/\/storymamas.com\/wp\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/storymamas.com\/wp\/category\/childrens-books\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/storymamas.com\/wp\/category\/childrens-books\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/storymamas.com\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Children's Books\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/storymamas.com\/wp\/#website\",\"url\":\"https:\/\/storymamas.com\/wp\/\",\"name\":\"Storymamas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/storymamas.com\/wp\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Children's Books Archives - Storymamas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/storymamas.com\/wp\/category\/childrens-books\/","og_locale":"en_US","og_type":"article","og_title":"Children's Books Archives - Storymamas","og_url":"https:\/\/storymamas.com\/wp\/category\/childrens-books\/","og_site_name":"Storymamas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/storymamas.com\/wp\/category\/childrens-books\/","url":"https:\/\/storymamas.com\/wp\/category\/childrens-books\/","name":"Children's Books Archives - Storymamas","isPartOf":{"@id":"https:\/\/storymamas.com\/wp\/#website"},"breadcrumb":{"@id":"https:\/\/storymamas.com\/wp\/category\/childrens-books\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/storymamas.com\/wp\/category\/childrens-books\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/storymamas.com\/wp\/"},{"@type":"ListItem","position":2,"name":"Children's Books"}]},{"@type":"WebSite","@id":"https:\/\/storymamas.com\/wp\/#website","url":"https:\/\/storymamas.com\/wp\/","name":"Storymamas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/storymamas.com\/wp\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/storymamas.com\/wp\/wp-json\/wp\/v2\/categories\/4"}],"collection":[{"href":"https:\/\/storymamas.com\/wp\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/storymamas.com\/wp\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/storymamas.com\/wp\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}